{"id":3980,"date":"2026-07-11T08:51:06","date_gmt":"2026-07-11T06:51:06","guid":{"rendered":"http:\/\/127.0.0.1\/mivoot\/mivoot2026\/wordpress\/?post_type=product&#038;p=3980"},"modified":"2026-07-24T14:00:13","modified_gmt":"2026-07-24T20:00:13","slug":"kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua","status":"publish","type":"product","link":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/","title":{"rendered":"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua"},"content":{"rendered":"<h1 style=\"text-align: center;\">Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua<\/h1>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/cdn.tvc.mx\/media\/2087248\/KIT-4G-ALARMAS.png\" \/><\/p>\n<p class=\"ql-align-justify\">Un dise\u00f1o completamente actual y un sistema tecnol\u00f3gico avanzado hacen que la nueva generaci\u00f3n de productos de alarma de intrusi\u00f3n inal\u00e1mbrica por medio de un HUB, sea mucho m\u00e1s f\u00e1cil de instalar, se vea mejor, se comunique de manera m\u00e1s confiable y funcione de manera estable. Desde la comodidad de las aplicaciones m\u00f3viles DMSS (iOS y Android), administre y controle sus dispositivos, reciba notificaciones en tiempo real, realice operaciones remotas y m\u00e1s.<\/p>\n<p>El kit contiene un concentrador de alarma de intrusi\u00f3n (HUB) modelo DHI-ARC3000H-FW2 para comunicaciones por cable Ethernet o WiFi; 4G, 3G o GPRS, un Sensor de Movimiento modelo DHI-ARD1233-W2, un Contacto Magn\u00e9tico modelo DHI-ARD323-W2 y un Control Remoto DHI-ARA24-W2<\/p>\n<h3>Principales Caracter\u00edsticas<\/h3>\n<ul>\n<li>Conexi\u00f3n del HUB por medio de red Ethernet por cable, o WiFi o 4G o 3G o GPRS<\/li>\n<li>Admite 150 perif\u00e9ricos inal\u00e1mbricos (6 sirenas, 64 llaveros inal\u00e1mbricos).<\/li>\n<li>Visualizaci\u00f3n del estado de los perif\u00e9ricos (intensidad de la se\u00f1al, nivel de bater\u00eda, temperatura, versi\u00f3n del firmware).<\/li>\n<li>Reposici\u00f3n autom\u00e1tica de red (ANR).<\/li>\n<li>Enlace de video en la aplicaci\u00f3n.<\/li>\n<li>Alarma de emergencia SOS.<\/li>\n<li>La funci\u00f3n de salto de frecuencia y la tecnolog\u00eda de comunicaci\u00f3n bidireccional garantizan la estabilidad de la comunicaci\u00f3n.<\/li>\n<li>Actualizaci\u00f3n en la nube y recuperaci\u00f3n autom\u00e1tica de fallas de actualizaci\u00f3n.<\/li>\n<\/ul>\n<h2>Protecci\u00f3n inteligente<\/h2>\n<p>Con la funci\u00f3n de salto de frecuencia (433,1 MHz\u2013434,6 MHz) y tecnolog\u00eda de comunicaci\u00f3n bidireccional encriptada en AES128, garantiza la estabilidad de la comunicaci\u00f3n. Adem\u00e1s, el dar de alta los dispositivos a trav\u00e9s de la App\u00a0DMSS\u00a0por medio de\u00a0c\u00f3digo\u00a0QR, hace muy sencilla la instalaci\u00f3n del sistema de alarma y sus dispositivos.<\/p>\n<p>La mayor\u00eda de los dispositivos cuentan con Indicador led de status de alarma,\u00a0tamper antisabotaje, medici\u00f3n y alarma de bater\u00eda baja del dispositivo, medici\u00f3n de temperatura ambiente, detecci\u00f3n de intensidad de se\u00f1al, Vinculaci\u00f3n Alarma &#8211; Sirena cuando se activa una alarma, Integraci\u00f3n Alarma &#8211; Video a trav\u00e9s de la App\u00a0DMSS\u00a0cuando se activa una alarma, configuraci\u00f3n remota, actualizaci\u00f3n en la nube y comprobaci\u00f3n del estado a trav\u00e9s de la aplicaci\u00f3n m\u00f3vil.<\/p>\n<h2>Especificaciones<\/h2>\n<ul>\n<li>Dimensiones empaque 219,0 mm \u00d7 187,0 mm \u00d7 91,0 mm (Largo \u00d7 Ancho \u00d7 Alto)<\/li>\n<li>Peso Bruto 1,150 g<\/li>\n<li>Carcasa de policarbonato y pl\u00e1stico ABS color blanco<\/li>\n<li>Funci\u00f3n de salto de frecuencia (433,1 MHz\u2013434,6 MHz) y tecnolog\u00eda de comunicaci\u00f3n bidireccional encriptada en AES128 garantizando la estabilidad de la comunicaci\u00f3n<\/li>\n<li>Actualizaci\u00f3n en la nube y recuperaci\u00f3n autom\u00e1tica de errores de actualizaci\u00f3n<\/li>\n<\/ul>\n<h2>Incluye<\/h2>\n<ul>\n<li><strong>1\u00d7\u00a0<\/strong>Panel de alarma<strong>\u00a0DHI-ART-ARC3000H-03-FW2<\/strong><\/li>\n<li><strong>1\u00d7<\/strong>\u00a0Control remoto inal\u00e1mbrico<\/li>\n<li><strong>1\u00d7<\/strong>\u00a0Sensor de puerta inal\u00e1mbrico<\/li>\n<li><strong>1\u00d7<\/strong>\u00a0Sensor de movimiento PIR inal\u00e1mbrico<\/li>\n<li><strong>1\u00d7<\/strong>\u00a0Adaptador de corriente<\/li>\n<li><strong>1x\u00a0<\/strong>Manual de usuario<\/li>\n<li><strong>1x<\/strong>\u00a0P\u00f3liza de garant\u00edas<\/li>\n<li>Accesorios de instalaci\u00f3n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Incluye los siguientes productos: DHI-ARC3000H-FW2, DHI-ARD1233-W2, DHI-ARA24-W2 y DHI-ARD323-W2(S)<br \/>\n&#8211; Admite 150 perif\u00e9ricos inal\u00e1mbricos<br \/>\n&#8211; 6 sirenas<br \/>\n&#8211; 64 llaveros inal\u00e1mbricos<br \/>\n&#8211; 4 repetidores de alarma<br \/>\n&#8211; 8 teclados inal\u00e1mbricos<br \/>\n&#8211; 8 c\u00e1maras PIR<br \/>\n&#8211; Visualizaci\u00f3n del estado de los perif\u00e9ricos<br \/>\n&#8211; intensidad de la se\u00f1al<br \/>\n&#8211; nivel de bater\u00eda<br \/>\n&#8211; temperatura<br \/>\n&#8211; versi\u00f3n del programa<br \/>\n&#8211; Conexi\u00f3n de red cableada, Wi-Fi, 4G, 3G o GPRS;<br \/>\n&#8211; Dual SIM y Single Standby, cambio autom\u00e1tico;<br \/>\n&#8211; Reposici\u00f3n autom\u00e1tica de red (ANR);<br \/>\n&#8211; Vinculaci\u00f3n de v\u00eddeo en la aplicaci\u00f3n;<br \/>\n&#8211; Llamada de emergencia SOS;<br \/>\n&#8211; La funci\u00f3n de salto de frecuencia y la tecnolog\u00eda de comunicaci\u00f3n bidireccional garantizan la estabilidad de la comunicaci\u00f3n;<br \/>\n&#8211; Actualizaci\u00f3n en la nube y recuperaci\u00f3n autom\u00e1tica en caso de fallo de actualizaci\u00f3n.<\/p>\n","protected":false},"featured_media":4122,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"pwb-brand":[275],"product_brand":[],"product_cat":[85],"product_tag":[],"class_list":["post-3980","product","type-product","status-publish","has-post-thumbnail","pwb-brand-dahua","product_cat-alarmas","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua - Mivoot Guatemala<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua\" \/>\n<meta property=\"og:description\" content=\"- Incluye los siguientes productos: DHI-ARC3000H-FW2, DHI-ARD1233-W2, DHI-ARA24-W2 y DHI-ARD323-W2(S) - Admite 150 perif\u00e9ricos inal\u00e1mbricos - 6 sirenas - 64 llaveros inal\u00e1mbricos - 4 repetidores de alarma - 8 teclados inal\u00e1mbricos - 8 c\u00e1maras PIR - Visualizaci\u00f3n del estado de los perif\u00e9ricos  - intensidad de la se\u00f1al - nivel de bater\u00eda - temperatura - versi\u00f3n del programa - Conexi\u00f3n de red cableada, Wi-Fi, 4G, 3G o GPRS; - Dual SIM y Single Standby, cambio autom\u00e1tico; - Reposici\u00f3n autom\u00e1tica de red (ANR); - Vinculaci\u00f3n de v\u00eddeo en la aplicaci\u00f3n; - Llamada de emergencia SOS; - La funci\u00f3n de salto de frecuencia y la tecnolog\u00eda de comunicaci\u00f3n bidireccional garantizan la estabilidad de la comunicaci\u00f3n; - Actualizaci\u00f3n en la nube y recuperaci\u00f3n autom\u00e1tica en caso de fallo de actualizaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/\" \/>\n<meta property=\"og:site_name\" content=\"Mivoot Guatemala\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mivootgt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-24T20:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mivoot.com\/gt\/wp-content\/uploads\/2026\/07\/ART-ARC3000H-03-FW2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/\",\"url\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/\",\"name\":\"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua - Mivoot Guatemala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ART-ARC3000H-03-FW2.png\",\"datePublished\":\"2026-07-11T06:51:06+00:00\",\"dateModified\":\"2026-07-24T20:00:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ART-ARC3000H-03-FW2.png\",\"contentUrl\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ART-ARC3000H-03-FW2.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alarmas\",\"item\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/categoria\\\/alarmas\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/#website\",\"url\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/\",\"name\":\"Mivoot\",\"description\":\"Mivoot Guatemala | Tienda Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/#organization\"},\"alternateName\":\"Mivoot Guatemala | Tienda Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/#organization\",\"name\":\"Mivoot - Tienda en Linea\",\"alternateName\":\"Mivoot\",\"url\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/mivoot-icono.ico\",\"contentUrl\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/mivoot-icono.ico\",\"width\":256,\"height\":239,\"caption\":\"Mivoot - Tienda en Linea\"},\"image\":{\"@id\":\"https:\\\/\\\/mivoot.com\\\/gt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mivootgt\"],\"description\":\"Productos que alteran tus sentidos encuentra la mejor tecnolog\u00eda en mivoot tienda online guatemala\",\"email\":\"info@mivoot.com\",\"telephone\":\"24296387\",\"legalName\":\"Mivoot\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua - Mivoot Guatemala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/","og_locale":"es_ES","og_type":"article","og_title":"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua","og_description":"- Incluye los siguientes productos: DHI-ARC3000H-FW2, DHI-ARD1233-W2, DHI-ARA24-W2 y DHI-ARD323-W2(S) - Admite 150 perif\u00e9ricos inal\u00e1mbricos - 6 sirenas - 64 llaveros inal\u00e1mbricos - 4 repetidores de alarma - 8 teclados inal\u00e1mbricos - 8 c\u00e1maras PIR - Visualizaci\u00f3n del estado de los perif\u00e9ricos  - intensidad de la se\u00f1al - nivel de bater\u00eda - temperatura - versi\u00f3n del programa - Conexi\u00f3n de red cableada, Wi-Fi, 4G, 3G o GPRS; - Dual SIM y Single Standby, cambio autom\u00e1tico; - Reposici\u00f3n autom\u00e1tica de red (ANR); - Vinculaci\u00f3n de v\u00eddeo en la aplicaci\u00f3n; - Llamada de emergencia SOS; - La funci\u00f3n de salto de frecuencia y la tecnolog\u00eda de comunicaci\u00f3n bidireccional garantizan la estabilidad de la comunicaci\u00f3n; - Actualizaci\u00f3n en la nube y recuperaci\u00f3n autom\u00e1tica en caso de fallo de actualizaci\u00f3n.","og_url":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/","og_site_name":"Mivoot Guatemala","article_publisher":"https:\/\/www.facebook.com\/mivootgt","article_modified_time":"2026-07-24T20:00:13+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/mivoot.com\/gt\/wp-content\/uploads\/2026\/07\/ART-ARC3000H-03-FW2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/","url":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/","name":"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua - Mivoot Guatemala","isPartOf":{"@id":"https:\/\/mivoot.com\/gt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/#primaryimage"},"image":{"@id":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/#primaryimage"},"thumbnailUrl":"https:\/\/mivoot.com\/gt\/wp-content\/uploads\/2026\/07\/ART-ARC3000H-03-FW2.png","datePublished":"2026-07-11T06:51:06+00:00","dateModified":"2026-07-24T20:00:13+00:00","breadcrumb":{"@id":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/#primaryimage","url":"https:\/\/mivoot.com\/gt\/wp-content\/uploads\/2026\/07\/ART-ARC3000H-03-FW2.png","contentUrl":"https:\/\/mivoot.com\/gt\/wp-content\/uploads\/2026\/07\/ART-ARC3000H-03-FW2.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/mivoot.com\/gt\/producto\/kit-de-panel-de-alarma-inalambrica-4g-wifi-ethernet-03-fw2-dahua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mivoot.com\/gt\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/mivoot.com\/gt\/producto\/"},{"@type":"ListItem","position":3,"name":"Alarmas","item":"https:\/\/mivoot.com\/gt\/categoria\/alarmas\/"},{"@type":"ListItem","position":4,"name":"Kit de Panel de Alarma Inal\u00e1mbrica 4G Wifi Ethernet 03-FW2 Dahua"}]},{"@type":"WebSite","@id":"https:\/\/mivoot.com\/gt\/#website","url":"https:\/\/mivoot.com\/gt\/","name":"Mivoot","description":"Mivoot Guatemala | Tienda Online","publisher":{"@id":"https:\/\/mivoot.com\/gt\/#organization"},"alternateName":"Mivoot Guatemala | Tienda Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mivoot.com\/gt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mivoot.com\/gt\/#organization","name":"Mivoot - Tienda en Linea","alternateName":"Mivoot","url":"https:\/\/mivoot.com\/gt\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mivoot.com\/gt\/#\/schema\/logo\/image\/","url":"https:\/\/mivoot.com\/gt\/wp-content\/uploads\/2026\/08\/mivoot-icono.ico","contentUrl":"https:\/\/mivoot.com\/gt\/wp-content\/uploads\/2026\/08\/mivoot-icono.ico","width":256,"height":239,"caption":"Mivoot - Tienda en Linea"},"image":{"@id":"https:\/\/mivoot.com\/gt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mivootgt"],"description":"Productos que alteran tus sentidos encuentra la mejor tecnolog\u00eda en mivoot tienda online guatemala","email":"info@mivoot.com","telephone":"24296387","legalName":"Mivoot"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"brands":[{"id":275,"name":"Dahua","slug":"dahua"}],"_links":{"self":[{"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/product\/3980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/comments?post=3980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/media\/4122"}],"wp:attachment":[{"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/media?parent=3980"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/pwb-brand?post=3980"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/product_brand?post=3980"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/product_cat?post=3980"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mivoot.com\/gt\/wp-json\/wp\/v2\/product_tag?post=3980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}